{"id":17177,"date":"2026-07-15T15:27:33","date_gmt":"2026-07-15T13:27:33","guid":{"rendered":"https:\/\/www.belfiorese.it\/new\/?p=17177"},"modified":"2026-07-15T15:28:54","modified_gmt":"2026-07-15T13:28:54","slug":"prima-categoria-colpo-in-attacco-preso-bomber-manuel-marcolini","status":"publish","type":"post","link":"https:\/\/www.belfiorese.it\/new\/index.php\/2026\/prima-categoria-colpo-in-attacco-preso-bomber-manuel-marcolini\/","title":{"rendered":"PRiMA CATEGORiA: COLPO iN ATTACCO, PRESO BOMBER MANUEL MARCOLiNi"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1021\" height=\"1024\" src=\"https:\/\/www.belfiorese.it\/new\/wp-content\/uploads\/2026\/07\/1000209643-1021x1024.jpg\" alt=\"\" class=\"wp-image-17201\" srcset=\"https:\/\/www.belfiorese.it\/new\/wp-content\/uploads\/2026\/07\/1000209643-1021x1024.jpg 1021w, https:\/\/www.belfiorese.it\/new\/wp-content\/uploads\/2026\/07\/1000209643-300x300.jpg 300w, https:\/\/www.belfiorese.it\/new\/wp-content\/uploads\/2026\/07\/1000209643-150x150.jpg 150w, https:\/\/www.belfiorese.it\/new\/wp-content\/uploads\/2026\/07\/1000209643-768x771.jpg 768w, https:\/\/www.belfiorese.it\/new\/wp-content\/uploads\/2026\/07\/1000209643-1531x1536.jpg 1531w, https:\/\/www.belfiorese.it\/new\/wp-content\/uploads\/2026\/07\/1000209643-2041x2048.jpg 2041w, https:\/\/www.belfiorese.it\/new\/wp-content\/uploads\/2026\/07\/1000209643-24x24.jpg 24w, https:\/\/www.belfiorese.it\/new\/wp-content\/uploads\/2026\/07\/1000209643-36x36.jpg 36w, https:\/\/www.belfiorese.it\/new\/wp-content\/uploads\/2026\/07\/1000209643-48x48.jpg 48w\" sizes=\"(max-width: 1021px) 100vw, 1021px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>PiU&#8217; Di 100 GOL ALL&#8217;ATTiVO<\/strong><\/h2>\n\n\n\n<p>In questo caldo caldissimo luglio a battere il ferro sul calcio mercato \u00e8 ancora una volta il direttore sportivo Claudio Giarolo che annuncia un altro gran colpo assicurandosi le prestazioni sportive del forte attaccante classe 1993 <strong>Manuel Marcolini<\/strong>. <\/p>\n\n\n\n<p>(<em>in foto con mister Meneghetti<\/em> )<\/p>\n\n\n\n<p>Trattativa decisa del DS biancazzurro per portare in riva all\u2019Adige l&#8217;<em>airone<\/em> Marcolini, un giocatore di esperienza che vanta gi\u00e0 115 reti in carriera e molti campionati in vetta alla classifica marcatori. Punta dinamica a cui piace aggredire la profondit\u00e0 e muoversi negli spazi senza palla, \u00e8 un calciatore che lavora molto per la squadra ma \u00e8 dotato di grande istinto e fiuto del gol. Un bomber di razza, il suo colpo migliore \u00e8 senza dubbio l&#8217;opportunismo nei sedici metri. <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-large is-resized\"><img decoding=\"async\" loading=\"lazy\" width=\"576\" height=\"1024\" src=\"https:\/\/www.belfiorese.it\/new\/wp-content\/uploads\/2026\/07\/1000209636-576x1024.jpg\" alt=\"\" class=\"wp-image-17202\" style=\"aspect-ratio:0.5625;width:199px;height:auto\" srcset=\"https:\/\/www.belfiorese.it\/new\/wp-content\/uploads\/2026\/07\/1000209636-576x1024.jpg 576w, https:\/\/www.belfiorese.it\/new\/wp-content\/uploads\/2026\/07\/1000209636-169x300.jpg 169w, https:\/\/www.belfiorese.it\/new\/wp-content\/uploads\/2026\/07\/1000209636-768x1365.jpg 768w, https:\/\/www.belfiorese.it\/new\/wp-content\/uploads\/2026\/07\/1000209636-864x1536.jpg 864w, https:\/\/www.belfiorese.it\/new\/wp-content\/uploads\/2026\/07\/1000209636-1152x2048.jpg 1152w, https:\/\/www.belfiorese.it\/new\/wp-content\/uploads\/2026\/07\/1000209636-14x24.jpg 14w, https:\/\/www.belfiorese.it\/new\/wp-content\/uploads\/2026\/07\/1000209636-20x36.jpg 20w, https:\/\/www.belfiorese.it\/new\/wp-content\/uploads\/2026\/07\/1000209636-27x48.jpg 27w, https:\/\/www.belfiorese.it\/new\/wp-content\/uploads\/2026\/07\/1000209636.jpg 1232w\" sizes=\"(max-width: 576px) 100vw, 576px\" \/><\/figure><\/div>\n\n\n<p>Una carriera costellata da tanti gol. Cresciuto calcisticamente nel vivaio dell&#8217;Audace, dopo tutta la trafila delle giovanili ha debuttato in prima squadra all&#8217;et\u00e0 di 17 anni (stagione 2010-11). Dopo 4 stagioni in maglia rossonera tra prima categoria e promozione viene tesserato dalla Speme di San Martino e vince i play-off di promozione. Nell&#8217;estate seguente passa al Montorio rimanendovi per 5 anni, tutti ad altissimo livello. Qui, sar\u00e0 uno dei protagonisti indiscussi della risalita trionfante dalla seconda categoria all&#8217;eccellenza: al termine del quinquennio realizza pi\u00f9 di 70 gol con un record personale di 31 reti nella sola stagione 2018-19. Nel 2021 si accasa nell&#8217;Albaronco e l&#8217;anno successivo ritorna all&#8217;Audace per altri due campionati (2022-2024). Guider\u00e0 poi l&#8217;attacco del Colognola ai Colli e contribuisce alla salvezza con i suoi 15 centri e assist. Inizia la scorsa stagione a Cadidavid ma nella finestra invernale di calcio mercato passa al Castel d&#8217;Azzano. <\/p>\n\n\n\n<p>Oggi sposa la causa della Belfiorese e non vede l&#8217;ora di scendere in campo con questi colori per iniziare la nuova avventura. E soprattutto, ha tanta grinta e fame di risultati.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>BENVENUTO MANUEL<\/strong><\/h2>\n\n\n\n<p>15 luglio 2026<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PiU&#8217; Di 100 GOL ALL&#8217;ATTiVO In questo caldo caldissimo luglio a battere il ferro sul calcio mercato \u00e8 ancora una volta il direttore sportivo Claudio Giarolo che annuncia un altro gran colpo assicurandosi le prestazioni sportive del forte attaccante classe 1993 Manuel Marcolini. (in foto con mister Meneghetti ) Trattativa [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":17201,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<title>PRiMA CATEGORiA: COLPO iN ATTACCO, PRESO BOMBER MANUEL MARCOLiNi - Polisportiva Dilettantistica Belfiorese<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.belfiorese.it\/new\/index.php\/2026\/prima-categoria-colpo-in-attacco-preso-bomber-manuel-marcolini\/\" \/>\r\n<meta property=\"og:locale\" content=\"it_IT\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"PRiMA CATEGORiA: COLPO iN ATTACCO, PRESO BOMBER MANUEL MARCOLiNi - Polisportiva Dilettantistica Belfiorese\" \/>\r\n<meta property=\"og:description\" content=\"PiU&#8217; Di 100 GOL ALL&#8217;ATTiVO In questo caldo caldissimo luglio a battere il ferro sul calcio mercato \u00e8 ancora una volta il direttore sportivo Claudio Giarolo che annuncia un altro gran colpo assicurandosi le prestazioni sportive del forte attaccante classe 1993 Manuel Marcolini. (in foto con mister Meneghetti ) Trattativa [&hellip;]\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.belfiorese.it\/new\/index.php\/2026\/prima-categoria-colpo-in-attacco-preso-bomber-manuel-marcolini\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Polisportiva Dilettantistica Belfiorese\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Belfiorese-117024602283911\" \/>\r\n<meta property=\"article:published_time\" content=\"2026-07-15T13:27:33+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2026-07-15T13:28:54+00:00\" \/>\r\n<meta property=\"og:image\" content=\"http:\/\/www.belfiorese.it\/new\/wp-content\/uploads\/2026\/07\/1000209643-scaled.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"2551\" \/>\r\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"Andrea Varco\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andrea Varco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.belfiorese.it\/new\/index.php\/2026\/prima-categoria-colpo-in-attacco-preso-bomber-manuel-marcolini\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.belfiorese.it\/new\/index.php\/2026\/prima-categoria-colpo-in-attacco-preso-bomber-manuel-marcolini\/\"},\"author\":{\"name\":\"Andrea Varco\",\"@id\":\"https:\/\/www.belfiorese.it\/new\/#\/schema\/person\/47d9b99f526d7d1671d98da993dd42ad\"},\"headline\":\"PRiMA CATEGORiA: COLPO iN ATTACCO, PRESO BOMBER MANUEL MARCOLiNi\",\"datePublished\":\"2026-07-15T13:27:33+00:00\",\"dateModified\":\"2026-07-15T13:28:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.belfiorese.it\/new\/index.php\/2026\/prima-categoria-colpo-in-attacco-preso-bomber-manuel-marcolini\/\"},\"wordCount\":305,\"publisher\":{\"@id\":\"https:\/\/www.belfiorese.it\/new\/#organization\"},\"articleSection\":[\"Calcio\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.belfiorese.it\/new\/index.php\/2026\/prima-categoria-colpo-in-attacco-preso-bomber-manuel-marcolini\/\",\"url\":\"https:\/\/www.belfiorese.it\/new\/index.php\/2026\/prima-categoria-colpo-in-attacco-preso-bomber-manuel-marcolini\/\",\"name\":\"PRiMA CATEGORiA: COLPO iN ATTACCO, PRESO BOMBER MANUEL MARCOLiNi - Polisportiva Dilettantistica Belfiorese\",\"isPartOf\":{\"@id\":\"https:\/\/www.belfiorese.it\/new\/#website\"},\"datePublished\":\"2026-07-15T13:27:33+00:00\",\"dateModified\":\"2026-07-15T13:28:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.belfiorese.it\/new\/index.php\/2026\/prima-categoria-colpo-in-attacco-preso-bomber-manuel-marcolini\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.belfiorese.it\/new\/index.php\/2026\/prima-categoria-colpo-in-attacco-preso-bomber-manuel-marcolini\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.belfiorese.it\/new\/index.php\/2026\/prima-categoria-colpo-in-attacco-preso-bomber-manuel-marcolini\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.belfiorese.it\/new\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PRiMA CATEGORiA: COLPO iN ATTACCO, PRESO BOMBER MANUEL MARCOLiNi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.belfiorese.it\/new\/#website\",\"url\":\"https:\/\/www.belfiorese.it\/new\/\",\"name\":\"Polisportiva Dilettantistica Belfiorese\",\"description\":\"Non chiederti MAI... cosa i tuoi compagni di squadra possono fare per te. Ma chiediti SEMPRE... cosa tu puoi fare per i tuoi compagni di squadra\",\"publisher\":{\"@id\":\"https:\/\/www.belfiorese.it\/new\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.belfiorese.it\/new\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.belfiorese.it\/new\/#organization\",\"name\":\"Polisportiva Dilettantistica Belfiorese\",\"url\":\"https:\/\/www.belfiorese.it\/new\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.belfiorese.it\/new\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.belfiorese.it\/new\/wp-content\/uploads\/2020\/09\/logo.png\",\"contentUrl\":\"https:\/\/www.belfiorese.it\/new\/wp-content\/uploads\/2020\/09\/logo.png\",\"width\":1350,\"height\":1500,\"caption\":\"Polisportiva Dilettantistica Belfiorese\"},\"image\":{\"@id\":\"https:\/\/www.belfiorese.it\/new\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Belfiorese-117024602283911\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.belfiorese.it\/new\/#\/schema\/person\/47d9b99f526d7d1671d98da993dd42ad\",\"name\":\"Andrea Varco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.belfiorese.it\/new\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/54a1fdd78c01dae98b60e85c8d6c600c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/54a1fdd78c01dae98b60e85c8d6c600c?s=96&d=mm&r=g\",\"caption\":\"Andrea Varco\"},\"url\":\"https:\/\/www.belfiorese.it\/new\/index.php\/author\/andreavarco\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PRiMA CATEGORiA: COLPO iN ATTACCO, PRESO BOMBER MANUEL MARCOLiNi - Polisportiva Dilettantistica Belfiorese","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.belfiorese.it\/new\/index.php\/2026\/prima-categoria-colpo-in-attacco-preso-bomber-manuel-marcolini\/","og_locale":"it_IT","og_type":"article","og_title":"PRiMA CATEGORiA: COLPO iN ATTACCO, PRESO BOMBER MANUEL MARCOLiNi - Polisportiva Dilettantistica Belfiorese","og_description":"PiU&#8217; Di 100 GOL ALL&#8217;ATTiVO In questo caldo caldissimo luglio a battere il ferro sul calcio mercato \u00e8 ancora una volta il direttore sportivo Claudio Giarolo che annuncia un altro gran colpo assicurandosi le prestazioni sportive del forte attaccante classe 1993 Manuel Marcolini. (in foto con mister Meneghetti ) Trattativa [&hellip;]","og_url":"https:\/\/www.belfiorese.it\/new\/index.php\/2026\/prima-categoria-colpo-in-attacco-preso-bomber-manuel-marcolini\/","og_site_name":"Polisportiva Dilettantistica Belfiorese","article_publisher":"https:\/\/www.facebook.com\/Belfiorese-117024602283911","article_published_time":"2026-07-15T13:27:33+00:00","article_modified_time":"2026-07-15T13:28:54+00:00","og_image":[{"width":2551,"height":2560,"url":"http:\/\/www.belfiorese.it\/new\/wp-content\/uploads\/2026\/07\/1000209643-scaled.jpg","type":"image\/jpeg"}],"author":"Andrea Varco","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Andrea Varco","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.belfiorese.it\/new\/index.php\/2026\/prima-categoria-colpo-in-attacco-preso-bomber-manuel-marcolini\/#article","isPartOf":{"@id":"https:\/\/www.belfiorese.it\/new\/index.php\/2026\/prima-categoria-colpo-in-attacco-preso-bomber-manuel-marcolini\/"},"author":{"name":"Andrea Varco","@id":"https:\/\/www.belfiorese.it\/new\/#\/schema\/person\/47d9b99f526d7d1671d98da993dd42ad"},"headline":"PRiMA CATEGORiA: COLPO iN ATTACCO, PRESO BOMBER MANUEL MARCOLiNi","datePublished":"2026-07-15T13:27:33+00:00","dateModified":"2026-07-15T13:28:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.belfiorese.it\/new\/index.php\/2026\/prima-categoria-colpo-in-attacco-preso-bomber-manuel-marcolini\/"},"wordCount":305,"publisher":{"@id":"https:\/\/www.belfiorese.it\/new\/#organization"},"articleSection":["Calcio"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.belfiorese.it\/new\/index.php\/2026\/prima-categoria-colpo-in-attacco-preso-bomber-manuel-marcolini\/","url":"https:\/\/www.belfiorese.it\/new\/index.php\/2026\/prima-categoria-colpo-in-attacco-preso-bomber-manuel-marcolini\/","name":"PRiMA CATEGORiA: COLPO iN ATTACCO, PRESO BOMBER MANUEL MARCOLiNi - Polisportiva Dilettantistica Belfiorese","isPartOf":{"@id":"https:\/\/www.belfiorese.it\/new\/#website"},"datePublished":"2026-07-15T13:27:33+00:00","dateModified":"2026-07-15T13:28:54+00:00","breadcrumb":{"@id":"https:\/\/www.belfiorese.it\/new\/index.php\/2026\/prima-categoria-colpo-in-attacco-preso-bomber-manuel-marcolini\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.belfiorese.it\/new\/index.php\/2026\/prima-categoria-colpo-in-attacco-preso-bomber-manuel-marcolini\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.belfiorese.it\/new\/index.php\/2026\/prima-categoria-colpo-in-attacco-preso-bomber-manuel-marcolini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.belfiorese.it\/new\/"},{"@type":"ListItem","position":2,"name":"PRiMA CATEGORiA: COLPO iN ATTACCO, PRESO BOMBER MANUEL MARCOLiNi"}]},{"@type":"WebSite","@id":"https:\/\/www.belfiorese.it\/new\/#website","url":"https:\/\/www.belfiorese.it\/new\/","name":"Polisportiva Dilettantistica Belfiorese","description":"Non chiederti MAI... cosa i tuoi compagni di squadra possono fare per te. Ma chiediti SEMPRE... cosa tu puoi fare per i tuoi compagni di squadra","publisher":{"@id":"https:\/\/www.belfiorese.it\/new\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.belfiorese.it\/new\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.belfiorese.it\/new\/#organization","name":"Polisportiva Dilettantistica Belfiorese","url":"https:\/\/www.belfiorese.it\/new\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.belfiorese.it\/new\/#\/schema\/logo\/image\/","url":"https:\/\/www.belfiorese.it\/new\/wp-content\/uploads\/2020\/09\/logo.png","contentUrl":"https:\/\/www.belfiorese.it\/new\/wp-content\/uploads\/2020\/09\/logo.png","width":1350,"height":1500,"caption":"Polisportiva Dilettantistica Belfiorese"},"image":{"@id":"https:\/\/www.belfiorese.it\/new\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Belfiorese-117024602283911"]},{"@type":"Person","@id":"https:\/\/www.belfiorese.it\/new\/#\/schema\/person\/47d9b99f526d7d1671d98da993dd42ad","name":"Andrea Varco","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.belfiorese.it\/new\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/54a1fdd78c01dae98b60e85c8d6c600c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/54a1fdd78c01dae98b60e85c8d6c600c?s=96&d=mm&r=g","caption":"Andrea Varco"},"url":"https:\/\/www.belfiorese.it\/new\/index.php\/author\/andreavarco\/"}]}},"_links":{"self":[{"href":"https:\/\/www.belfiorese.it\/new\/index.php\/wp-json\/wp\/v2\/posts\/17177"}],"collection":[{"href":"https:\/\/www.belfiorese.it\/new\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.belfiorese.it\/new\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.belfiorese.it\/new\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.belfiorese.it\/new\/index.php\/wp-json\/wp\/v2\/comments?post=17177"}],"version-history":[{"count":9,"href":"https:\/\/www.belfiorese.it\/new\/index.php\/wp-json\/wp\/v2\/posts\/17177\/revisions"}],"predecessor-version":[{"id":17205,"href":"https:\/\/www.belfiorese.it\/new\/index.php\/wp-json\/wp\/v2\/posts\/17177\/revisions\/17205"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.belfiorese.it\/new\/index.php\/wp-json\/wp\/v2\/media\/17201"}],"wp:attachment":[{"href":"https:\/\/www.belfiorese.it\/new\/index.php\/wp-json\/wp\/v2\/media?parent=17177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.belfiorese.it\/new\/index.php\/wp-json\/wp\/v2\/categories?post=17177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.belfiorese.it\/new\/index.php\/wp-json\/wp\/v2\/tags?post=17177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}